{"id":1477,"count":1,"description":"","link":"https:\/\/center-for-entrepreneurship.reutlingen-university.de\/en\/tag\/internship\/","name":"Internship","slug":"internship","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Internship Archive - Center for Entrepreneurship<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/center-for-entrepreneurship.reutlingen-university.de\/en\/tag\/internship\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Internship Archive - Center for Entrepreneurship\" \/>\n<meta property=\"og:url\" content=\"https:\/\/center-for-entrepreneurship.reutlingen-university.de\/en\/tag\/internship\/\" \/>\n<meta property=\"og:site_name\" content=\"Center for Entrepreneurship\" \/>\n<meta property=\"og:image\" content=\"https:\/\/center-for-entrepreneurship.reutlingen-university.de\/wp-content\/uploads\/2020\/04\/Open-Graph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ReutlingenCE\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/center-for-entrepreneurship.reutlingen-university.de\\\/en\\\/tag\\\/internship\\\/\",\"url\":\"https:\\\/\\\/center-for-entrepreneurship.reutlingen-university.de\\\/en\\\/tag\\\/internship\\\/\",\"name\":\"Internship Archive - Center for Entrepreneurship\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/center-for-entrepreneurship.reutlingen-university.de\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/center-for-entrepreneurship.reutlingen-university.de\\\/en\\\/tag\\\/internship\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/center-for-entrepreneurship.reutlingen-university.de\\\/en\\\/tag\\\/internship\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/center-for-entrepreneurship.reutlingen-university.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Internship\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/center-for-entrepreneurship.reutlingen-university.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/center-for-entrepreneurship.reutlingen-university.de\\\/en\\\/\",\"name\":\"Center for Entrepreneurship\",\"description\":\"Das Gr\u00fcndungszentrum der Hochschule Reutlingen f\u00fcr Studierende und Gr\u00fcndungsinteressierte.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/center-for-entrepreneurship.reutlingen-university.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Internship Archive - Center for Entrepreneurship","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/center-for-entrepreneurship.reutlingen-university.de\/en\/tag\/internship\/","og_locale":"en_US","og_type":"article","og_title":"Internship Archive - Center for Entrepreneurship","og_url":"https:\/\/center-for-entrepreneurship.reutlingen-university.de\/en\/tag\/internship\/","og_site_name":"Center for Entrepreneurship","og_image":[{"width":800,"height":500,"url":"https:\/\/center-for-entrepreneurship.reutlingen-university.de\/wp-content\/uploads\/2020\/04\/Open-Graph.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ReutlingenCE","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/center-for-entrepreneurship.reutlingen-university.de\/en\/tag\/internship\/","url":"https:\/\/center-for-entrepreneurship.reutlingen-university.de\/en\/tag\/internship\/","name":"Internship Archive - Center for Entrepreneurship","isPartOf":{"@id":"https:\/\/center-for-entrepreneurship.reutlingen-university.de\/en\/#website"},"breadcrumb":{"@id":"https:\/\/center-for-entrepreneurship.reutlingen-university.de\/en\/tag\/internship\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/center-for-entrepreneurship.reutlingen-university.de\/en\/tag\/internship\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/center-for-entrepreneurship.reutlingen-university.de\/en\/"},{"@type":"ListItem","position":2,"name":"Internship"}]},{"@type":"WebSite","@id":"https:\/\/center-for-entrepreneurship.reutlingen-university.de\/en\/#website","url":"https:\/\/center-for-entrepreneurship.reutlingen-university.de\/en\/","name":"Center for Entrepreneurship","description":"Das Gr\u00fcndungszentrum der Hochschule Reutlingen f\u00fcr Studierende und Gr\u00fcndungsinteressierte.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/center-for-entrepreneurship.reutlingen-university.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/center-for-entrepreneurship.reutlingen-university.de\/en\/wp-json\/wp\/v2\/tags\/1477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/center-for-entrepreneurship.reutlingen-university.de\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/center-for-entrepreneurship.reutlingen-university.de\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/center-for-entrepreneurship.reutlingen-university.de\/en\/wp-json\/wp\/v2\/posts?tags=1477"},{"href":"https:\/\/center-for-entrepreneurship.reutlingen-university.de\/en\/wp-json\/wp\/v2\/tribe_events?tags=1477"},{"href":"https:\/\/center-for-entrepreneurship.reutlingen-university.de\/en\/wp-json\/wp\/v2\/tec_calendar_embed?tags=1477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}